{"id":3598,"date":"2016-06-23T11:39:36","date_gmt":"2016-06-23T15:39:36","guid":{"rendered":"http:\/\/www.organogold.com\/ph-en\/personal-care\/"},"modified":"2024-08-12T11:01:04","modified_gmt":"2024-08-12T18:01:04","slug":"personal-care","status":"publish","type":"page","link":"https:\/\/www.organogold.com\/ph-en\/personal-care\/","title":{"rendered":"Personal Care"},"content":{"rendered":"<p>[vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/3&#8243; alignment=&#8221;center&#8221;]<div data-id=\"mpc_flipbox-996a57341b66d2b\" class=\"mpc-flipbox mpc-init mpc-flipbox--flip-left \" ><div class=\"mpc-flipbox__content\" data-front-align=\"middle-center\" data-back-align=\"middle-center\"><div class=\"mpc-flipbox__front\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\"><div data-id=\"mpc_image-786a57341b675d8\" onclick=\"\" class=\"mpc-image mpc-init \" ><div class=\"mpc-item mpc-transition\"><img width=\"550\" height=\"550\" src=\"https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/06\/OG-smile.jpg\" class=\"mpc-transition attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/06\/OG-smile.jpg 550w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/06\/OG-smile-150x150.jpg 150w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/06\/OG-smile-300x300.jpg 300w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/06\/OG-smile-146x146.jpg 146w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/06\/OG-smile-50x50.jpg 50w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/06\/OG-smile-75x75.jpg 75w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/06\/OG-smile-85x85.jpg 85w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/06\/OG-smile-80x80.jpg 80w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-flipbox__back mpc-container\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\">[vc_column_text css=&#8221;.vc_custom_1542236399152{margin-right: 20px !important;margin-left: 20px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse bo-prodnum-408 ix-prodnum-2465\" href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\">Buy Now<\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/protect-toothpaste\/\">Product Details<\/a><\/p>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Protect Toothpaste&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;]<div data-id=\"mpc_flipbox-696a57341b676a5\" class=\"mpc-flipbox mpc-init mpc-flipbox--flip-left \" ><div class=\"mpc-flipbox__content\" data-front-align=\"middle-center\" data-back-align=\"middle-center\"><div class=\"mpc-flipbox__front\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\"><div data-id=\"mpc_image-616a57341b67cf2\" onclick=\"\" class=\"mpc-image mpc-init \" ><div class=\"mpc-item mpc-transition\"><img width=\"528\" height=\"430\" src=\"https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/08\/Shampoo_Bar.jpg\" class=\"mpc-transition attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/08\/Shampoo_Bar.jpg 528w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/08\/Shampoo_Bar-300x244.jpg 300w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/08\/Shampoo_Bar-179x146.jpg 179w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/08\/Shampoo_Bar-50x41.jpg 50w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/08\/Shampoo_Bar-92x75.jpg 92w\" sizes=\"(max-width: 528px) 100vw, 528px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-flipbox__back mpc-container\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\">[vc_column_text css=&#8221;.vc_custom_1723485642490{margin-right: 20px !important;margin-left: 20px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse bo-prodnum-1622 ix-prodnum-2461\" href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\">Buy Now<\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/shampoo-bar\/\">Product Details<\/a><\/p>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Shampoo Bar&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;]<div data-id=\"mpc_flipbox-296a57341b67dc3\" class=\"mpc-flipbox mpc-init mpc-flipbox--flip-left \" ><div class=\"mpc-flipbox__content\" data-front-align=\"middle-center\" data-back-align=\"middle-center\"><div class=\"mpc-flipbox__front\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\"><div data-id=\"mpc_image-386a57341b684c9\" onclick=\"\" class=\"mpc-image mpc-init \" ><div class=\"mpc-item mpc-transition\"><img width=\"430\" height=\"528\" src=\"https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/08\/balm.png\" class=\"mpc-transition attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/08\/balm.png 430w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/08\/balm-244x300.png 244w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/08\/balm-119x146.png 119w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/08\/balm-41x50.png 41w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/08\/balm-61x75.png 61w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-flipbox__back mpc-container\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\">[vc_column_text css=&#8221;.vc_custom_1723485653075{margin-right: 20px !important;margin-left: 20px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse bo-prodnum-6800 ix-prodnum-2466\" href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\">Buy Now<\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/balm\/\">Product Details<\/a><\/p>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Balm&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/3&#8243; alignment=&#8221;center&#8221;]<div data-id=\"mpc_flipbox-16a57341b68595\" class=\"mpc-flipbox mpc-init mpc-flipbox--flip-left \" ><div class=\"mpc-flipbox__content\" data-front-align=\"middle-center\" data-back-align=\"middle-center\"><div class=\"mpc-flipbox__front\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\"><div data-id=\"mpc_image-696a57341b68bc5\" onclick=\"\" class=\"mpc-image mpc-init \" ><div class=\"mpc-item mpc-transition\"><img width=\"550\" height=\"550\" src=\"https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/09\/g3_soap-1.jpg\" class=\"mpc-transition attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/09\/g3_soap-1.jpg 550w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/09\/g3_soap-1-150x150.jpg 150w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/09\/g3_soap-1-300x300.jpg 300w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/09\/g3_soap-1-146x146.jpg 146w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/09\/g3_soap-1-50x50.jpg 50w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/09\/g3_soap-1-75x75.jpg 75w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/09\/g3_soap-1-85x85.jpg 85w, https:\/\/www.organogold.com\/wp-content\/uploads\/2016\/09\/g3_soap-1-80x80.jpg 80w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-flipbox__back mpc-container\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\">[vc_column_text css=&#8221;.vc_custom_1723485446119{margin-right: 20px !important;margin-left: 20px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse bo-prodnum-408 ix-prodnum-2462\" href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\">Buy Now<\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/premium-g3-beauty-soap\/\">Product Details<\/a><\/p>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Premium G3 Beauty Soap&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/3&#8243; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Protect Toothpaste&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Shampoo Bar&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Balm&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/3&#8243; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Personal Care - Organo Gold<\/title>\n<meta name=\"description\" content=\"ORGANO is a global leader in ganoderma-enhanced coffee and beverages, providing life changing opportunities with expanded portfolio in all-natural skincare, travel services, payment solutions and more.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.organogold.com\/ph-en\/personal-care\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Personal Care - Organo Gold\" \/>\n<meta property=\"og:description\" content=\"ORGANO is a global leader in ganoderma-enhanced coffee and beverages, providing life changing opportunities with expanded portfolio in all-natural skincare, travel services, payment solutions and more.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.organogold.com\/ph-en\/personal-care\/\" \/>\n<meta property=\"og:site_name\" content=\"Organo Gold\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/organogold\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-12T18:01:04+00:00\" \/>\n<meta property=\"fb:app_id\" content=\"1781016228881841\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OrganoGold\" \/>\n<meta name=\"twitter:site\" content=\"@OrganoGold\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.organogold.com\/ph-en\/#website\",\"url\":\"https:\/\/www.organogold.com\/ph-en\/\",\"name\":\"Organo Gold\",\"description\":\"Organo Gold\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.organogold.com\/ph-en\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.organogold.com\/ph-en\/personal-care\/#webpage\",\"url\":\"http:\/\/www.organogold.com\/ph-en\/personal-care\/\",\"name\":\"Personal Care - Organo Gold\",\"isPartOf\":{\"@id\":\"https:\/\/www.organogold.com\/ph-en\/#website\"},\"datePublished\":\"2016-06-23T15:39:36+00:00\",\"dateModified\":\"2024-08-12T18:01:04+00:00\",\"description\":\"ORGANO is a global leader in ganoderma-enhanced coffee and beverages, providing life changing opportunities with expanded portfolio in all-natural skincare, travel services, payment solutions and more.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.organogold.com\/ph-en\/personal-care\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/www.organogold.com\/ph-en\/wp-json\/wp\/v2\/pages\/3598"}],"collection":[{"href":"https:\/\/www.organogold.com\/ph-en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.organogold.com\/ph-en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.organogold.com\/ph-en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.organogold.com\/ph-en\/wp-json\/wp\/v2\/comments?post=3598"}],"version-history":[{"count":6,"href":"https:\/\/www.organogold.com\/ph-en\/wp-json\/wp\/v2\/pages\/3598\/revisions"}],"predecessor-version":[{"id":90570,"href":"https:\/\/www.organogold.com\/ph-en\/wp-json\/wp\/v2\/pages\/3598\/revisions\/90570"}],"wp:attachment":[{"href":"https:\/\/www.organogold.com\/ph-en\/wp-json\/wp\/v2\/media?parent=3598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}