{"id":84003,"date":"2022-10-05T12:00:24","date_gmt":"2022-10-05T19:00:24","guid":{"rendered":"http:\/\/www.organogold.com\/royal-black-coffee\/"},"modified":"2023-02-14T10:53:42","modified_gmt":"2023-02-14T18:53:42","slug":"royal-black-coffee","status":"publish","type":"page","link":"https:\/\/www.organogold.com\/at-it\/royal-black-coffee\/","title":{"rendered":"Royal Black Coffee"},"content":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1665077560490{padding-top: 8% !important;padding-bottom: 8% !important;background-color: #231f20 !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h1 style=\"text-align: center; color: #dc965a;\"><strong>Gli Ingredienti fanno la differenza nel Royal<\/strong><\/h1>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner content_placement=&#8221;middle&#8221; gap=&#8221;35&#8243;][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83759&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css_animation=&#8221;fadeInLeft&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text css_animation=&#8221;none&#8221;]<\/p>\n<h4 style=\"color: #fff;\">I prodotti migliori hanno sempre gli ingredienti migliori. Abbiamo cercato ci\u00f2 che di meglio la natura ha da offrire. Unisciti a noi mentre esploriamo questi incredibili ingredienti.<\/h4>\n<p>[\/vc_column_text][vc_empty_space]<a href=\"https:\/\/ogmarketing.s3.ca-central-1.amazonaws.com\/videos\/productrelease\/ROYAL+LAUNCH+PT2+-+MUSHROOM+SEGMENT+FOR+WEBSITE+LANDING+PAGE+v2+101222.mp4\" target=\"_blank\" title=\"\"  class=\"mpc-lightbox mpc-init mpc-transition mpc-magnific-popup \"><div data-id=\"mpc_button-576a57dab9d26ac\" class=\"mpc-button mpc-init mpc-transition \" ><div class=\"mpc-button__content mpc-effect-type--none mpc-effect-side--none\"><span class=\"mpc-button__title mpc-transition\">Watch Video<\/span><\/div><div class=\"mpc-button__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/div><\/a>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1665078751095{padding-top: 8% !important;background-color: #040404 !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83146&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css_animation=&#8221;fadeInLeft&#8221;][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h1 style=\"color: #dc5454; text-align: left;\"><strong>Il fungo Reishi<\/strong><\/h1>\n<p>[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h3 style=\"color: #dc965a; text-align: left;\">Ganoderma Lucidum<\/h3>\n<p>[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h4 style=\"color: #fff;\">Gli antichi cinesi riservavano il Reishi alla nobilt\u00e0 e lo chiamavano il fungo dell&#8217;immortalit\u00e0 per descrivere il supporto onnicomprensivo che poteva fornire. Ora, migliaia di anni dopo, puoi avere questo fungo a casa tua.<\/h4>\n<p>[\/vc_column_text][vc_empty_space][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83155&#8243; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Contribuisce alle difese immunologiche naturali<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83177&#8243; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Inizia una giornata senza stress<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column_inner][\/vc_row_inner][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83175&#8243; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Inizia una giornata senza stress<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_hidden-lg vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;][vc_single_image image=&#8221;83176&#8243; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Aids in longevity<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1665078758253{padding-top: 8% !important;background-color: #040404 !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83142&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css_animation=&#8221;fadeInLeft&#8221;][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h1 style=\"color: #dea978; text-align: left;\"><strong>CORDYCEPS<\/strong><\/h1>\n<p>[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h4 style=\"color: #fff;\">Adagiato ai piedi delle montagne himalayane si trova il raro fungo Cordyceps. \u00c8 stato utilizzato per centinaia di anni da cinesi e tibetani che credevano che avesse una moltitudine di effetti benefici. Tuttavia, a causa della sua rarit\u00e0, era riservato ai reali&#8230; fino ad ora.<\/h4>\n<p>[\/vc_column_text][vc_empty_space][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83191&#8243; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Goditi un gusto morbido e mai amaro<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83190&#8243; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Goditi un gusto morbido e mai amaro<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column_inner][\/vc_row_inner][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83189&#8243; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Cambia il tuo stato d&#8217;animo<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83188&#8243; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Patrimonio asiatico<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1665078820923{padding-top: 8% !important;padding-bottom: 8% !important;background-color: #040404 !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83141&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css_animation=&#8221;fadeInLeft&#8221;][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h1 style=\"color: #ffffff; text-align: left;\"><strong>LION\u2019S MANE<\/strong><\/h1>\n<p>[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h4 style=\"color: #fff;\">Gli antichi cinesi veneravano il Lion&#8217;s Mane per le sue capacit\u00e0 di potenziamento cognitivo come l&#8217;aumento della concentrazione, della memoria e dell&#8217;attenzione. I monaci buddisti usavano spesso questo fungo per energizzare le loro menti e concentrarsi maggiormente durante la meditazione.<\/h4>\n<p>[\/vc_column_text][vc_empty_space][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83187&#8243; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Prova la differenza<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83186&#8243; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Mangia consapevolmente<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column_inner][\/vc_row_inner][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83185&#8243; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Mangia consapevolmente<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1665593505385{padding-top: 8% !important;padding-bottom: 4% !important;background-color: #0a3f7c !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h1 style=\"color: #ffffff; text-align: left;\"><strong>Lo sapevi?<\/strong><\/h1>\n<p>[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h4 style=\"color: #fff;\">I funghi assorbono il loro cibo dall&#8217;esterno, proprio come fanno gli animali. L&#8217;ambiente in cui crescono influisce sulla qualit\u00e0 dei composti e dei nutrienti che si trovano in essi. Il Ganoderma, il Cordyceps e il Lion&#8217;s Mane, che costituiscono la nostra miscela di funghi, sono coltivati su un mais viola non OGM. Ci\u00f2 si traduce in un maggiore valore nutritivo e in una naturale espressione di micronutrienti.<\/h4>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83757&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column][vc_column][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<h3 style=\"color: #ffffff; text-align: left;\"><strong>La Miscela Tripla di Funghi \u00e8 anche:<\/strong><\/h3>\n<h4 style=\"color: #ffffff; text-align: left;\">Certificata biologica | Vegana | Senza glutine | Non OGM | Senza pesticidi | Non irradiata | Esente da BSE\/TSE | Senza melamina | Senza solventi residui | Cresciuta negli Stati Uniti<\/h4>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1665166318157{padding-top: 5% !important;padding-bottom: 5% !important;background-image: url(https:\/\/www.organogold.com\/wp-content\/uploads\/2022\/10\/beans-bg.png?id=83258) !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1674849125094{margin-top: 5% !important;margin-bottom: 5% !important;}&#8221;]<\/p>\n<h1 style=\"text-align: center; color: #000;\"><strong>Chicchi di caff\u00e8<\/strong><\/h1>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243; css=&#8221;.vc_custom_1665168654459{padding-top: 8% !important;padding-right: 6% !important;padding-bottom: 8% !important;padding-left: 6% !important;background-color: rgba(0,0,0,0.43) !important;*background-color: rgb(0,0,0) !important;border-radius: 5px !important;}&#8221;][vc_column_text]<\/p>\n<h4 style=\"text-align: center; color: #fff;\">Il Gourmet ROYAL Black by ORGANO contiene chicchi di caff\u00e8 provenienti dalla Colombia e dal Brasile, coltivati per conferire quel profilo morbido e quei sentori di cioccolato che tutti amano per un infuso perfetto.<\/h4>\n<p>&nbsp;<\/p>\n<h4 style=\"text-align: center; color: #fff;\">Con un sapore ricco e robusto racchiuso in ogni tazza, questo integratore alimentare offre tutto il gusto di una tazza di caff\u00e8, arricchito dai benefici della miscela di funghi tripli di Ganoderma, Cordyceps e Lion&#8217;s Mane.<\/h4>\n<p>[\/vc_column_text][vc_empty_space][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_empty_space][vc_single_image image=&#8221;83271&#8243; alignment=&#8221;center&#8221;][vc_empty_space][vc_column_text]<\/p>\n<p style=\"color: #ffffff; text-align: center;\"><strong>Infuso con tripla miscela di funghi<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_empty_space][vc_single_image image=&#8221;83270&#8243; alignment=&#8221;center&#8221;][vc_empty_space][vc_column_text]<\/p>\n<p style=\"color: #ffffff; text-align: center;\"><strong>Dal ricco e robusto sapore <\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_empty_space][vc_single_image image=&#8221;83272&#8243; alignment=&#8221;center&#8221;][vc_empty_space][vc_column_text]<\/p>\n<p style=\"color: #ffffff; text-align: center;\"><strong>Combinazione ideale di grani di caff\u00e8 Arabica e Robusta <\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1665082810340{padding-top: 2% !important;padding-bottom: 2% !important;background-color: #231f20 !important;}&#8221;][vc_column][vc_single_image image=&#8221;83144&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_empty_space][vc_column_text]<\/p>\n<h1 style=\"text-align: center; color: #dc965a;\"><strong>Il Caff\u00e8 Gourmet incontra la Regalit\u00e0<\/strong><\/h1>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<h4 style=\"color: #ffffff; text-align: center;\">Questo esclusivo integratore alimentare a tripla miscela di funghi combina l&#8217;integrazione con i sapori morbidi e ricchi del nostro caff\u00e8 gourmet. Il tutto avvolto in una confezione monodose. Goditi i benefici nutrizionali e il gusto premium in ogni tazza!<\/h4>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner content_placement=&#8221;middle&#8221; gap=&#8221;35&#8243;][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;83224&#8243; alignment=&#8221;center&#8221; css_animation=&#8221;fadeInLeft&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text css_animation=&#8221;fadeInLeft&#8221;]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Vegano<\/p>\n<p>[\/vc_column_text][vc_empty_space][vc_empty_space][vc_single_image image=&#8221;83223&#8243; alignment=&#8221;center&#8221; css_animation=&#8221;fadeInLeft&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text css_animation=&#8221;fadeInLeft&#8221;]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Senza noci<\/p>\n<p>[\/vc_column_text][vc_empty_space][vc_empty_space][vc_single_image image=&#8221;83222&#8243; alignment=&#8221;center&#8221; css_animation=&#8221;fadeInLeft&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text css_animation=&#8221;fadeInLeft&#8221;]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Prodotto in Canada<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;83212&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;83221&#8243; alignment=&#8221;center&#8221; css_animation=&#8221;fadeInRight&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text css_animation=&#8221;fadeInRight&#8221;]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Non OGM<\/p>\n<p>[\/vc_column_text][vc_empty_space][vc_empty_space][vc_single_image image=&#8221;83220&#8243; alignment=&#8221;center&#8221; css_animation=&#8221;fadeInRight&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text css_animation=&#8221;fadeInRight&#8221;]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Senza glutine<\/p>\n<p>[\/vc_column_text][vc_empty_space][vc_empty_space][vc_single_image image=&#8221;83219&#8243; alignment=&#8221;center&#8221; css_animation=&#8221;fadeInRight&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text css_animation=&#8221;fadeInRight&#8221;]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Senza zucchero<\/p>\n<p>[\/vc_column_text][vc_empty_space][vc_empty_space][vc_single_image image=&#8221;83218&#8243; alignment=&#8221;center&#8221; css_animation=&#8221;fadeInRight&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_column_text css_animation=&#8221;fadeInRight&#8221;]<\/p>\n<p style=\"color: #ffffff; text-align: center;\">Certificato Halal<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;83143&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; full_height=&#8221;yes&#8221; enable_parallax=&#8221;true&#8221; parallax_background=&#8221;83344&#8243; parallax_style=&#8221;fixed&#8221;][vc_column][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1669753586765{padding-top: 8% !important;padding-bottom: 8% !important;background-color: #06182b !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h1 style=\"text-align: center; color: #dc965a;\"><strong>BENEFITS FROM THE FIRST SIP<\/strong><\/h1>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1669753523323{padding-top: 8% !important;padding-bottom: 8% !important;background-color: #06182b !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83758&#8243; img_size=&#8221;full&#8221;][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;83246&#8243; alignment=&#8221;center&#8221;][vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text]<\/p>\n<h2 style=\"color: #ffffff; text-align: left; font-weight: bold;\">Increases Energy<\/h2>\n<p>[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h4 style=\"color: #ffffff; text-align: left;\">Provides you with the energy you need to enhance physical and mental performance.<\/h4>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8221;64px&#8221;][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;83155&#8243; alignment=&#8221;center&#8221;][vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text]<\/p>\n<h2 style=\"color: #ffffff; text-align: left; font-weight: bold;\">Powers Immunity<\/h2>\n<p>[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h4 style=\"color: #ffffff; text-align: left;\">Boosts immunity to keep your mind and body feeling amazing.<\/h4>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8221;64px&#8221;][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;83245&#8243; alignment=&#8221;center&#8221;][vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text]<\/p>\n<h2 style=\"color: #ffffff; text-align: left; font-weight: bold;\">Elevates Focus<\/h2>\n<p>[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h4 style=\"color: #ffffff; text-align: left;\">Boosts your cognitive function for better focus and attention.<\/h4>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_empty_space][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-white ix-prodnum-3591\" href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\">BUY NOW<\/a><span style=\"font-size: 20px; color: #fff; font-weight: bold; margin-left: 15px;\">Thank us later!<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1669753623808{padding-top: 8% !important;padding-bottom: 8% !important;background-color: #06182b !important;}&#8221;][vc_column][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_empty_space][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-white ix-prodnum-3591\" href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> Acquistalo ora e ci ringrazierai! <\/a><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1665439654525{padding-top: 6% !important;padding-bottom: 6% !important;background-image: url(https:\/\/www.organogold.com\/wp-content\/uploads\/2022\/10\/Group-10000027021.png?id=83280) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;faq&#8221;][vc_column][vc_column_text]<\/p>\n<h1 style=\"color: #fff;\">FAQs<\/h1>\n<p>[\/vc_column_text][vc_empty_space][vc_row_inner equal_height=&#8221;yes&#8221; gap=&#8221;35&#8243;][vc_column_inner el_class=&#8221;popmake-84715&#8243; width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1676400727350{padding-top: 25px !important;padding-bottom: 25px !important;background-color: #ffffff !important;border-radius: 5px !important;}&#8221;][vc_single_image image=&#8221;83325&#8243; alignment=&#8221;center&#8221;][vc_empty_space][vc_column_text css_animation=&#8221;none&#8221;]<\/p>\n<h4 style=\"color: #000; text-align: center;\">THE COMPOSITION<\/h4>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;popmake-84738&#8243; width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1676400763492{padding-top: 25px !important;padding-bottom: 25px !important;background-color: #ffffff !important;border-radius: 5px !important;}&#8221;][vc_single_image image=&#8221;83324&#8243; alignment=&#8221;center&#8221;][vc_empty_space][vc_column_text css_animation=&#8221;none&#8221;]<\/p>\n<h4 style=\"color: #000; text-align: center;\">THE PREPARATION<\/h4>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;popmake-84761&#8243; width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1676400780391{padding-top: 25px !important;padding-bottom: 25px !important;background-color: #ffffff !important;border-radius: 5px !important;}&#8221;][vc_single_image image=&#8221;83323&#8243; alignment=&#8221;center&#8221;][vc_empty_space][vc_column_text css_animation=&#8221;none&#8221;]<\/p>\n<h4 style=\"color: #000; text-align: center;\">THE ORIGIN<\/h4>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; gap=&#8221;35&#8243;][vc_column_inner el_class=&#8221;popmake-84784&#8243; width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1676400788232{padding-top: 25px !important;padding-bottom: 25px !important;background-color: #ffffff !important;border-radius: 5px !important;}&#8221;][vc_single_image image=&#8221;83322&#8243; alignment=&#8221;center&#8221;][vc_empty_space][vc_column_text css_animation=&#8221;none&#8221;]<\/p>\n<h4 style=\"color: #000; text-align: center;\">THE AUTHENTICITY<\/h4>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;popmake-84806&#8243; width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1676400805411{padding-top: 25px !important;padding-bottom: 25px !important;background-color: #ffffff !important;border-radius: 5px !important;}&#8221;][vc_single_image image=&#8221;83321&#8243; alignment=&#8221;center&#8221;][vc_empty_space][vc_column_text css_animation=&#8221;none&#8221;]<\/p>\n<h4 style=\"color: #000; text-align: center;\">WHY SO SPECIAL?<\/h4>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;popmake-84829&#8243; width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1676400811961{padding-top: 25px !important;padding-bottom: 25px !important;background-color: #ffffff !important;border-radius: 5px !important;}&#8221;][vc_single_image image=&#8221;83320&#8243; alignment=&#8221;center&#8221;][vc_empty_space][vc_column_text css_animation=&#8221;none&#8221;]<\/p>\n<h4 style=\"color: #000; text-align: center;\">IS IT TRUE?<\/h4>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1665077560490{padding-top: 8% !important;padding-bottom: 8% !important;background-color: #231f20 !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text] Gli Ingredienti fanno la differenza nel Royal [\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner content_placement=&#8221;middle&#8221; gap=&#8221;35&#8243;][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;83759&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Royal Black Coffee - Organo Gold<\/title>\n<meta name=\"description\" content=\"ORGANO is a global leader in ganoderma-enhanced coffee and beverages, providing life changing opportunities with expanded portfolio in all-natural skincare, travel services, payment solutions and more.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.organogold.com\/at-it\/royal-black-coffee\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Royal Black Coffee - Organo Gold\" \/>\n<meta property=\"og:description\" content=\"ORGANO is a global leader in ganoderma-enhanced coffee and beverages, providing life changing opportunities with expanded portfolio in all-natural skincare, travel services, payment solutions and more.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.organogold.com\/at-it\/royal-black-coffee\/\" \/>\n<meta property=\"og:site_name\" content=\"Organo Gold\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/organogold\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-14T18:53:42+00:00\" \/>\n<meta property=\"fb:app_id\" content=\"1781016228881841\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OrganoGold\" \/>\n<meta name=\"twitter:site\" content=\"@OrganoGold\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.organogold.com\/at-it\/#website\",\"url\":\"https:\/\/www.organogold.com\/at-it\/\",\"name\":\"Organo Gold\",\"description\":\"Organo Gold\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.organogold.com\/at-it\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.organogold.com\/at-it\/royal-black-coffee\/#webpage\",\"url\":\"http:\/\/www.organogold.com\/at-it\/royal-black-coffee\/\",\"name\":\"Royal Black Coffee - Organo Gold\",\"isPartOf\":{\"@id\":\"https:\/\/www.organogold.com\/at-it\/#website\"},\"datePublished\":\"2022-10-05T19:00:24+00:00\",\"dateModified\":\"2023-02-14T18:53:42+00:00\",\"description\":\"ORGANO is a global leader in ganoderma-enhanced coffee and beverages, providing life changing opportunities with expanded portfolio in all-natural skincare, travel services, payment solutions and more.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.organogold.com\/at-it\/royal-black-coffee\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/www.organogold.com\/at-it\/wp-json\/wp\/v2\/pages\/84003"}],"collection":[{"href":"https:\/\/www.organogold.com\/at-it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.organogold.com\/at-it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.organogold.com\/at-it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.organogold.com\/at-it\/wp-json\/wp\/v2\/comments?post=84003"}],"version-history":[{"count":10,"href":"https:\/\/www.organogold.com\/at-it\/wp-json\/wp\/v2\/pages\/84003\/revisions"}],"predecessor-version":[{"id":85427,"href":"https:\/\/www.organogold.com\/at-it\/wp-json\/wp\/v2\/pages\/84003\/revisions\/85427"}],"wp:attachment":[{"href":"https:\/\/www.organogold.com\/at-it\/wp-json\/wp\/v2\/media?parent=84003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}